{"id":11073,"date":"2026-05-03T20:01:04","date_gmt":"2026-05-03T11:01:04","guid":{"rendered":"https:\/\/gachapara.jp\/?p=11073"},"modified":"2026-05-01T10:47:22","modified_gmt":"2026-05-01T01:47:22","slug":"tous-sont-de-type-hoho-nouvelle-capsule-pocket","status":"publish","type":"post","link":"https:\/\/gachapara.jp\/fr\/11073\/","title":{"rendered":"Tous sont de type Ho-Oo ! Nouveau jouet en capsule : 'Collection Pok\u00e9mon Swing Type : Feu'."},"content":{"rendered":"<p>Une collection de jouets en capsule de Pok\u00e9mon de type feu dans la collection Pok\u00e9mon Swing.<\/p>\n<p>Il est livr\u00e9 avec une cha\u00eene \u00e0 boules qui peut \u00eatre attach\u00e9e \u00e0 votre sac ou \u00e0 vos cl\u00e9s, ce qui le rend parfait pour \u00eatre transport\u00e9. La gamme comprend Lizardon, Booster, Bakuhun, Victini et Fokko.<\/p>\n<p>Ils co\u00fbtent 300 yens chacun et seront disponibles \u00e0 partir de la quatri\u00e8me semaine de mai 2026.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gachapara.jp\/wp-content\/uploads\/2026\/04\/1000250069_1.jpg\" alt=\"GACHA GACHA : &#039;Collection Pok\u00e9mon Swing Type:Feu&#039;.\" width=\"1200\" height=\"1200\" class=\"alignnone size-full wp-image-11075\" srcset=\"https:\/\/gachapara.jp\/wp-content\/uploads\/2026\/04\/1000250069_1.jpg 1200w, https:\/\/gachapara.jp\/wp-content\/uploads\/2026\/04\/1000250069_1-300x300.jpg 300w, https:\/\/gachapara.jp\/wp-content\/uploads\/2026\/04\/1000250069_1-1024x1024.jpg 1024w, https:\/\/gachapara.jp\/wp-content\/uploads\/2026\/04\/1000250069_1-150x150.jpg 150w, https:\/\/gachapara.jp\/wp-content\/uploads\/2026\/04\/1000250069_1-768x768.jpg 768w, https:\/\/gachapara.jp\/wp-content\/uploads\/2026\/04\/1000250069_1-12x12.jpg 12w, https:\/\/gachapara.jp\/wp-content\/uploads\/2026\/04\/1000250069_1-485x485.jpg 485w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><span class=\"bizcaption\">(*Image tir\u00e9e du site web officiel\/du SRS officiel)<\/span><\/p>\n<h2 class=\"wp-block-heading\">\u25a0Gachapara focus \u00e9ditorial.<\/h2>\n<ul>\n<li>Collection de balan\u00e7oires Pocket Monster.<\/li>\n<li>Avec cha\u00eene \u00e0 boules pour attacher les sacs et les cl\u00e9s.<\/li>\n<li>Alignement de cinq Pok\u00e9mon de type feu.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\">\u25a0 Aper\u00e7u du produit.<\/h2>\n<ul>\n<li>Collection Pok\u00e9mon Swing Type:Feu<\/li>\n<li>5 esp\u00e8ces<\/li>\n<li>300 yens<\/li>\n<li>Publi\u00e9 par : Bandai Co.<\/li>\n<li>Date de lancement : 4\u00e8me semaine de mai 2026 -.<\/li>\n<\/ul>\n<p>*Les informations sont correctes au moment de la publication.<br \/>\n*Peut \u00eatre en rupture de stock.<br \/>\n*L'heure de sortie et d'arriv\u00e9e peut varier selon les r\u00e9gions et les magasins. Certains magasins peuvent ne pas avoir le produit en stock ou peuvent changer sans pr\u00e9avis.<br \/>\nLes droits d'auteur et de marque des produits et des noms cit\u00e9s sur ce site appartiennent aux fabricants et aux d\u00e9tenteurs des droits d'auteur respectifs.<br \/>\n*Les images sont en cours de d\u00e9veloppement et le design et le contenu peuvent diff\u00e9rer en partie du produit r\u00e9el.<br \/>\nToutefois, en cas de divergence de contenu, les informations figurant sur le site officiel pr\u00e9valent. Veuillez comprendre cela \u00e0 l'avance avant d'utiliser ce site web.<\/p>\n<p>&lt;Reportage, r\u00e9daction et \u00e9dition par l&#039;\u00e9quipe \u00e9ditoriale de Gachapara.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u30dd\u30b1\u30c3\u30c8\u30e2\u30f3\u30b9\u30bf\u30fc\u306e\u30b9\u30a4\u30f3\u30b0\u30b3\u30ec\u30af\u30b7\u30e7\u30f3\u306b\u3001\u307b\u306e\u304a\u30bf\u30a4\u30d7\u306e\u30dd\u30b1\u30e2\u30f3\u305f\u3061\u304c\u30ab\u30d7\u30bb\u30eb\u30c8\u30a4\u3067\u5927\u96c6\u5408\u3002 \u30ab\u30d0\u30f3\u3084\u9375\u306b\u53d6\u308a\u4ed8\u3051\u3089\u308c\u308b\u30dc\u30fc\u30eb\u30c1\u30a7\u30fc\u30f3\u4ed8\u304d\u3067\u3001\u6301\u3061\u6b69\u304d\u306b\u3082\u3074\u3063\u305f\u308a\u3067\u3059\u3002\u30ea\u30b6\u30fc\u30c9\u30f3\u3001\u30d6\u30fc\u30b9\u30bf\u30fc\u3001\u30d0\u30af\u30d5\u30fc\u30f3\u3001\u30d3\u30af\u30c6\u30a3\u30cb\u3001\u30d5&#8230;<\/p>","protected":false},"author":3,"featured_media":11075,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[117,118,116,119,115],"class_list":{"0":"post-11073","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-capsule-toy","8":"tag-117","9":"tag-118","10":"tag-116","11":"tag-119","12":"tag-115","13":"article"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/gachapara.jp\/fr\/wp-json\/wp\/v2\/posts\/11073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gachapara.jp\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gachapara.jp\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gachapara.jp\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gachapara.jp\/fr\/wp-json\/wp\/v2\/comments?post=11073"}],"version-history":[{"count":3,"href":"https:\/\/gachapara.jp\/fr\/wp-json\/wp\/v2\/posts\/11073\/revisions"}],"predecessor-version":[{"id":11325,"href":"https:\/\/gachapara.jp\/fr\/wp-json\/wp\/v2\/posts\/11073\/revisions\/11325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gachapara.jp\/fr\/wp-json\/wp\/v2\/media\/11075"}],"wp:attachment":[{"href":"https:\/\/gachapara.jp\/fr\/wp-json\/wp\/v2\/media?parent=11073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gachapara.jp\/fr\/wp-json\/wp\/v2\/categories?post=11073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gachapara.jp\/fr\/wp-json\/wp\/v2\/tags?post=11073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}